{"id":3677,"date":"2026-04-01T08:43:00","date_gmt":"2026-04-01T08:43:00","guid":{"rendered":"https:\/\/redwoodyoga.de\/?p=3677"},"modified":"2026-05-13T10:24:32","modified_gmt":"2026-05-13T10:24:32","slug":"leben-im-jetzt-meditation-achtsamkeit-im-alltag-training","status":"publish","type":"post","link":"https:\/\/redwoodyoga.de\/en\/leben-im-jetzt-meditation-achtsamkeit-im-alltag-training","title":{"rendered":"Leben im Jetzt &#8211; Meditation &amp; Achtsamkeit im Alltag (Wochenend-Seminar)"},"content":{"rendered":"\n<p>In unserer hektischen und schnelllebigen Welt suchen immer mehr Menschen nach M\u00f6glichkeiten, um ihre innere Balance zu finden, Stress abzubauen und ihr pers\u00f6nliches Wohlbefinden zu steigern. In diesem Zusammenhang haben sich Meditation und Achtsamkeit als \u00e4u\u00dferst effektive Werkzeuge erwiesen. In diesem Training tauchen wir in uralte und moderne Praktiken ein und lernen wie sie in den Alltag und die Yogapraxis integriert werden k\u00f6nnen.<\/p>\n\n\n\n<p>Die Meditation ist eine jahrhundertealte Praxis, bei der durch Konzentration und Fokussierung der Geist beruhigt wird. Sie hilft dabei, den Fluss der Gedanken zu beobachten, inneren Frieden zu finden und Stress abzubauen. In diesem Training erlernen wir verschiedene Meditationstechniken und wie diese einzusetzen sind.<\/p>\n\n\n\n<p>Achtsamkeit ist ein weiteres wichtiges Element des Training. Sie bezieht sich auf das bewusste Wahrnehmen und Akzeptieren des gegenw\u00e4rtigen Augenblicks, ohne dabei zu bewerten oder zu urteilen. Wir bringen die Achtsamkeit von der Matte in das echte Leben hinein und schauen uns an wie Achtsamkeit unseren Alltag, Beziehungen und unsere Ern\u00e4hrung bereichern kann.<\/p>\n\n\n\n<p>Neben der Philosophie der Achtsamkeit besch\u00e4ftigen wir uns auch mit den Praktiken des Stoizismus, eine philosophische Lehre aus dem antiken Griechenland. Der Stoizismus lehrt die Kunst der Gelassenheit und die Akzeptanz dessen, was nicht kontrolliert werden kann. Die Teilnehmer lernen, wie sie stoische Prinzipien in ihr Leben integrieren k\u00f6nnen, um mit den Herausforderungen des Alltags umzugehen, innere St\u00e4rke zu entwickeln und ihre Perspektive auf schwierige Situationen zu ver\u00e4ndern. Der Stoizismus bietet praktische Werkzeuge, um eine positive Einstellung zu kultivieren und sich auf das Wesentliche zu konzentrieren.<\/p>\n\n\n\n<p>In der Training werden Theorie und Praxis miteinander verbunden. Neben theoretischem Hintergrundwissen erhalten die Teilnehmer die M\u00f6glichkeit, die verschiedenen Techniken selbst zu erproben und in der Gruppe zu reflektieren. Durch regelm\u00e4\u00dfige \u00dcbung und den Austausch mit anderen Teilnehmern k\u00f6nnen sie ihre Kenntnisse vertiefen und ihre pers\u00f6nliche Entwicklung vorantreiben.<\/p>\n\n\n\n<p><strong>Details<\/strong><br>19. &#8211; 21.02.2027 <br>Freitag 17.30-20.30<br>Samstag &amp; Sonntag jeweils 8.30 &#8211; 17.30 (1h Mittagspause)<\/p>\n\n\n\n<p>Diese Fortbildung ist f\u00fcr Yogalehrer:innen und fortgeschrittene Sch\u00fcler:innen geeignet.<br>Sie ist Bestandteil der <a href=\"https:\/\/redwoodyoga.de\/300h-yogalehrerin-ausbildung\">300 Stunden Ausbildung<\/a>, kann jedoch auch einzeln gebucht werden.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-ad2f72ca wp-block-group-is-layout-flex\">\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-fill\"><a class=\"wp-block-button__link has-luminous-vivid-amber-background-color has-background wp-element-button\" href=\"https:\/\/redwoodyoga.de\/300h-yogalehrerin-ausbildung\">zur 300h Ausbildung<\/a><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-luminous-vivid-amber-background-color has-background wp-element-button\" href=\"https:\/\/redwoodyoga.de\/fortbildungen\">Buchen<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:27% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/redwoodyoga.de\/wp-content\/uploads\/2024\/12\/Redwoodyoga_Sandra-Dienemann-Fotografie-030-scaled-e1738055379295-1024x1024.jpg\" alt=\"\" class=\"wp-image-3678 size-medium\" srcset=\"https:\/\/redwoodyoga.de\/wp-content\/uploads\/2024\/12\/Redwoodyoga_Sandra-Dienemann-Fotografie-030-scaled-e1738055379295-1024x1024.jpg 1024w, https:\/\/redwoodyoga.de\/wp-content\/uploads\/2024\/12\/Redwoodyoga_Sandra-Dienemann-Fotografie-030-scaled-e1738055379295-600x600.jpg 600w, https:\/\/redwoodyoga.de\/wp-content\/uploads\/2024\/12\/Redwoodyoga_Sandra-Dienemann-Fotografie-030-scaled-e1738055379295-768x768.jpg 768w, https:\/\/redwoodyoga.de\/wp-content\/uploads\/2024\/12\/Redwoodyoga_Sandra-Dienemann-Fotografie-030-scaled-e1738055379295-1536x1536.jpg 1536w, https:\/\/redwoodyoga.de\/wp-content\/uploads\/2024\/12\/Redwoodyoga_Sandra-Dienemann-Fotografie-030-scaled-e1738055379295.jpg 1708w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p>Meet your Teachers:<\/p>\n\n\n\n<p>Die Fortbildung wird von E-RYT 500 Yogalehrerin und Studiogr\u00fcnderin Annalena und Yogalehrer Kalyan geleitet. Beide haben mit renommierten internationalen Yogalehrer:innen wie Mark Stephens oder Dylan Werner studiert. Aus ihrem gro\u00dfen Erfahrungsschatz verschiedenster Philosophien bringen sie an diesem Wochenende das Beste zusammen um es dir leichter zu machen die Achtsamkeit in dein Leben zu integrieren.<\/p>\n\n\n\n<p><\/p>\n<\/div><\/div>\n\n\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In unserer hektischen und schnelllebigen Welt suchen immer mehr Menschen nach M\u00f6glichkeiten, um ihre innere Balance zu finden, Stress abzubauen und ihr pers\u00f6nliches Wohlbefinden zu steigern. In diesem Zusammenhang haben &hellip; <\/p>\n","protected":false},"author":1,"featured_media":3678,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16,50],"tags":[131,132,12,94,117,10],"class_list":["post-3677","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuelles","category-fortbildungen","tag-achtsamkeit","tag-bewusst-leben","tag-bonn","tag-fortbildung","tag-training","tag-yoga"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Leben im Jetzt - Meditation &amp; Achtsamkeit im Alltag (Wochenend-Seminar) - Redwood Yoga<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redwoodyoga.de\/leben-im-jetzt-meditation-achtsamkeit-im-alltag-training\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Leben im Jetzt - Meditation &amp; Achtsamkeit im Alltag (Wochenend-Seminar) - Redwood Yoga\" \/>\n<meta property=\"og:description\" content=\"In unserer hektischen und schnelllebigen Welt suchen immer mehr Menschen nach M\u00f6glichkeiten, um ihre innere Balance zu finden, Stress abzubauen und ihr pers\u00f6nliches Wohlbefinden zu steigern. In diesem Zusammenhang haben &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redwoodyoga.de\/leben-im-jetzt-meditation-achtsamkeit-im-alltag-training\" \/>\n<meta property=\"og:site_name\" content=\"Redwood Yoga\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-01T08:43:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T10:24:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redwoodyoga.de\/wp-content\/uploads\/2024\/12\/Redwoodyoga_Sandra-Dienemann-Fotografie-030-scaled-e1738055379295.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1708\" \/>\n\t<meta property=\"og:image:height\" content=\"1708\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redwood-Yoga\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redwood-Yoga\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/redwoodyoga.de\/leben-im-jetzt-meditation-achtsamkeit-im-alltag-training#article\",\"isPartOf\":{\"@id\":\"https:\/\/redwoodyoga.de\/leben-im-jetzt-meditation-achtsamkeit-im-alltag-training\"},\"author\":{\"name\":\"Redwood-Yoga\",\"@id\":\"https:\/\/redwoodyoga.de\/#\/schema\/person\/3289abb7f25c0e8ee5b6d53530dfd7e3\"},\"headline\":\"Leben im Jetzt &#8211; Meditation &amp; Achtsamkeit im Alltag (Wochenend-Seminar)\",\"datePublished\":\"2026-04-01T08:43:00+00:00\",\"dateModified\":\"2026-05-13T10:24:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/redwoodyoga.de\/leben-im-jetzt-meditation-achtsamkeit-im-alltag-training\"},\"wordCount\":417,\"publisher\":{\"@id\":\"https:\/\/redwoodyoga.de\/#organization\"},\"image\":{\"@id\":\"https:\/\/redwoodyoga.de\/leben-im-jetzt-meditation-achtsamkeit-im-alltag-training#primaryimage\"},\"thumbnailUrl\":\"https:\/\/redwoodyoga.de\/wp-content\/uploads\/2024\/12\/Redwoodyoga_Sandra-Dienemann-Fotografie-030-scaled-e1738055379295.jpg\",\"keywords\":[\"Achtsamkeit\",\"bewusst leben\",\"bonn\",\"Fortbildung\",\"Training\",\"yoga\"],\"articleSection\":[\"Aktuelles\",\"Fortbildungen\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/redwoodyoga.de\/leben-im-jetzt-meditation-achtsamkeit-im-alltag-training\",\"url\":\"https:\/\/redwoodyoga.de\/leben-im-jetzt-meditation-achtsamkeit-im-alltag-training\",\"name\":\"Leben im Jetzt - Meditation &amp; Achtsamkeit im Alltag (Wochenend-Seminar) - Redwood Yoga\",\"isPartOf\":{\"@id\":\"https:\/\/redwoodyoga.de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/redwoodyoga.de\/leben-im-jetzt-meditation-achtsamkeit-im-alltag-training#primaryimage\"},\"image\":{\"@id\":\"https:\/\/redwoodyoga.de\/leben-im-jetzt-meditation-achtsamkeit-im-alltag-training#primaryimage\"},\"thumbnailUrl\":\"https:\/\/redwoodyoga.de\/wp-content\/uploads\/2024\/12\/Redwoodyoga_Sandra-Dienemann-Fotografie-030-scaled-e1738055379295.jpg\",\"datePublished\":\"2026-04-01T08:43:00+00:00\",\"dateModified\":\"2026-05-13T10:24:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/redwoodyoga.de\/leben-im-jetzt-meditation-achtsamkeit-im-alltag-training#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/redwoodyoga.de\/leben-im-jetzt-meditation-achtsamkeit-im-alltag-training\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/redwoodyoga.de\/leben-im-jetzt-meditation-achtsamkeit-im-alltag-training#primaryimage\",\"url\":\"https:\/\/redwoodyoga.de\/wp-content\/uploads\/2024\/12\/Redwoodyoga_Sandra-Dienemann-Fotografie-030-scaled-e1738055379295.jpg\",\"contentUrl\":\"https:\/\/redwoodyoga.de\/wp-content\/uploads\/2024\/12\/Redwoodyoga_Sandra-Dienemann-Fotografie-030-scaled-e1738055379295.jpg\",\"width\":1708,\"height\":1708},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/redwoodyoga.de\/leben-im-jetzt-meditation-achtsamkeit-im-alltag-training#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\/\/redwoodyoga.de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Leben im Jetzt &#8211; Meditation &amp; Achtsamkeit im Alltag (Wochenend-Seminar)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/redwoodyoga.de\/#website\",\"url\":\"https:\/\/redwoodyoga.de\/\",\"name\":\"Redwood Yoga\",\"description\":\"wachse \u00fcber dich hinaus\",\"publisher\":{\"@id\":\"https:\/\/redwoodyoga.de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/redwoodyoga.de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/redwoodyoga.de\/#organization\",\"name\":\"Redwood Yoga\",\"url\":\"https:\/\/redwoodyoga.de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/redwoodyoga.de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/redwoodyoga.de\/wp-content\/uploads\/2019\/02\/finishedlogomitkreis-e1631539893616.png\",\"contentUrl\":\"https:\/\/redwoodyoga.de\/wp-content\/uploads\/2019\/02\/finishedlogomitkreis-e1631539893616.png\",\"width\":70,\"height\":70,\"caption\":\"Redwood Yoga\"},\"image\":{\"@id\":\"https:\/\/redwoodyoga.de\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/redwoodyoga.de\/#\/schema\/person\/3289abb7f25c0e8ee5b6d53530dfd7e3\",\"name\":\"Redwood-Yoga\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/redwoodyoga.de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d3ec880672e7951c131e4480cca64ebb8e8e1d9eac1dfe0bb0d61e0fa0637e0c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d3ec880672e7951c131e4480cca64ebb8e8e1d9eac1dfe0bb0d61e0fa0637e0c?s=96&d=mm&r=g\",\"caption\":\"Redwood-Yoga\"},\"url\":\"https:\/\/redwoodyoga.de\/en\/author\/redwood-yoga\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Leben im Jetzt - Meditation &amp; Achtsamkeit im Alltag (Wochenend-Seminar) - Redwood Yoga","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redwoodyoga.de\/leben-im-jetzt-meditation-achtsamkeit-im-alltag-training","og_locale":"en_US","og_type":"article","og_title":"Leben im Jetzt - Meditation &amp; Achtsamkeit im Alltag (Wochenend-Seminar) - Redwood Yoga","og_description":"In unserer hektischen und schnelllebigen Welt suchen immer mehr Menschen nach M\u00f6glichkeiten, um ihre innere Balance zu finden, Stress abzubauen und ihr pers\u00f6nliches Wohlbefinden zu steigern. In diesem Zusammenhang haben &hellip;","og_url":"https:\/\/redwoodyoga.de\/leben-im-jetzt-meditation-achtsamkeit-im-alltag-training","og_site_name":"Redwood Yoga","article_published_time":"2026-04-01T08:43:00+00:00","article_modified_time":"2026-05-13T10:24:32+00:00","og_image":[{"width":1708,"height":1708,"url":"https:\/\/redwoodyoga.de\/wp-content\/uploads\/2024\/12\/Redwoodyoga_Sandra-Dienemann-Fotografie-030-scaled-e1738055379295.jpg","type":"image\/jpeg"}],"author":"Redwood-Yoga","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Redwood-Yoga","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redwoodyoga.de\/leben-im-jetzt-meditation-achtsamkeit-im-alltag-training#article","isPartOf":{"@id":"https:\/\/redwoodyoga.de\/leben-im-jetzt-meditation-achtsamkeit-im-alltag-training"},"author":{"name":"Redwood-Yoga","@id":"https:\/\/redwoodyoga.de\/#\/schema\/person\/3289abb7f25c0e8ee5b6d53530dfd7e3"},"headline":"Leben im Jetzt &#8211; Meditation &amp; Achtsamkeit im Alltag (Wochenend-Seminar)","datePublished":"2026-04-01T08:43:00+00:00","dateModified":"2026-05-13T10:24:32+00:00","mainEntityOfPage":{"@id":"https:\/\/redwoodyoga.de\/leben-im-jetzt-meditation-achtsamkeit-im-alltag-training"},"wordCount":417,"publisher":{"@id":"https:\/\/redwoodyoga.de\/#organization"},"image":{"@id":"https:\/\/redwoodyoga.de\/leben-im-jetzt-meditation-achtsamkeit-im-alltag-training#primaryimage"},"thumbnailUrl":"https:\/\/redwoodyoga.de\/wp-content\/uploads\/2024\/12\/Redwoodyoga_Sandra-Dienemann-Fotografie-030-scaled-e1738055379295.jpg","keywords":["Achtsamkeit","bewusst leben","bonn","Fortbildung","Training","yoga"],"articleSection":["Aktuelles","Fortbildungen"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/redwoodyoga.de\/leben-im-jetzt-meditation-achtsamkeit-im-alltag-training","url":"https:\/\/redwoodyoga.de\/leben-im-jetzt-meditation-achtsamkeit-im-alltag-training","name":"Leben im Jetzt - Meditation &amp; Achtsamkeit im Alltag (Wochenend-Seminar) - Redwood Yoga","isPartOf":{"@id":"https:\/\/redwoodyoga.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redwoodyoga.de\/leben-im-jetzt-meditation-achtsamkeit-im-alltag-training#primaryimage"},"image":{"@id":"https:\/\/redwoodyoga.de\/leben-im-jetzt-meditation-achtsamkeit-im-alltag-training#primaryimage"},"thumbnailUrl":"https:\/\/redwoodyoga.de\/wp-content\/uploads\/2024\/12\/Redwoodyoga_Sandra-Dienemann-Fotografie-030-scaled-e1738055379295.jpg","datePublished":"2026-04-01T08:43:00+00:00","dateModified":"2026-05-13T10:24:32+00:00","breadcrumb":{"@id":"https:\/\/redwoodyoga.de\/leben-im-jetzt-meditation-achtsamkeit-im-alltag-training#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redwoodyoga.de\/leben-im-jetzt-meditation-achtsamkeit-im-alltag-training"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/redwoodyoga.de\/leben-im-jetzt-meditation-achtsamkeit-im-alltag-training#primaryimage","url":"https:\/\/redwoodyoga.de\/wp-content\/uploads\/2024\/12\/Redwoodyoga_Sandra-Dienemann-Fotografie-030-scaled-e1738055379295.jpg","contentUrl":"https:\/\/redwoodyoga.de\/wp-content\/uploads\/2024\/12\/Redwoodyoga_Sandra-Dienemann-Fotografie-030-scaled-e1738055379295.jpg","width":1708,"height":1708},{"@type":"BreadcrumbList","@id":"https:\/\/redwoodyoga.de\/leben-im-jetzt-meditation-achtsamkeit-im-alltag-training#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/redwoodyoga.de\/"},{"@type":"ListItem","position":2,"name":"Leben im Jetzt &#8211; Meditation &amp; Achtsamkeit im Alltag (Wochenend-Seminar)"}]},{"@type":"WebSite","@id":"https:\/\/redwoodyoga.de\/#website","url":"https:\/\/redwoodyoga.de\/","name":"Redwood Yoga","description":"wachse \u00fcber dich hinaus","publisher":{"@id":"https:\/\/redwoodyoga.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redwoodyoga.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/redwoodyoga.de\/#organization","name":"Redwood Yoga","url":"https:\/\/redwoodyoga.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/redwoodyoga.de\/#\/schema\/logo\/image\/","url":"https:\/\/redwoodyoga.de\/wp-content\/uploads\/2019\/02\/finishedlogomitkreis-e1631539893616.png","contentUrl":"https:\/\/redwoodyoga.de\/wp-content\/uploads\/2019\/02\/finishedlogomitkreis-e1631539893616.png","width":70,"height":70,"caption":"Redwood Yoga"},"image":{"@id":"https:\/\/redwoodyoga.de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/redwoodyoga.de\/#\/schema\/person\/3289abb7f25c0e8ee5b6d53530dfd7e3","name":"Redwood-Yoga","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/redwoodyoga.de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d3ec880672e7951c131e4480cca64ebb8e8e1d9eac1dfe0bb0d61e0fa0637e0c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d3ec880672e7951c131e4480cca64ebb8e8e1d9eac1dfe0bb0d61e0fa0637e0c?s=96&d=mm&r=g","caption":"Redwood-Yoga"},"url":"https:\/\/redwoodyoga.de\/en\/author\/redwood-yoga"}]}},"_links":{"self":[{"href":"https:\/\/redwoodyoga.de\/en\/wp-json\/wp\/v2\/posts\/3677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redwoodyoga.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redwoodyoga.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redwoodyoga.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redwoodyoga.de\/en\/wp-json\/wp\/v2\/comments?post=3677"}],"version-history":[{"count":9,"href":"https:\/\/redwoodyoga.de\/en\/wp-json\/wp\/v2\/posts\/3677\/revisions"}],"predecessor-version":[{"id":4722,"href":"https:\/\/redwoodyoga.de\/en\/wp-json\/wp\/v2\/posts\/3677\/revisions\/4722"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redwoodyoga.de\/en\/wp-json\/wp\/v2\/media\/3678"}],"wp:attachment":[{"href":"https:\/\/redwoodyoga.de\/en\/wp-json\/wp\/v2\/media?parent=3677"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redwoodyoga.de\/en\/wp-json\/wp\/v2\/categories?post=3677"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redwoodyoga.de\/en\/wp-json\/wp\/v2\/tags?post=3677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}